{"id":3809,"date":"2020-09-19T12:36:42","date_gmt":"2020-09-19T12:36:42","guid":{"rendered":"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/"},"modified":"2022-09-19T12:47:28","modified_gmt":"2022-09-19T12:47:28","slug":"el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc","status":"publish","type":"post","link":"https:\/\/fundaciomiquelvalls.org\/es\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/","title":{"rendered":"El planteamiento de la Terapia Ocupacional en la Fundaci\u00f3n Miquel Valls\ufffc"},"content":{"rendered":"\n<p>En la Terapia Ocupacional se realiza un planteamiento hol\u00edstico de la persona, es decir, en nuestro trabajo no s\u00f3lo nos centramos en la persona afectada de ELA sino tambi\u00e9n en su entorno f\u00edsico y social.<\/p>\n\n\n\n<p>Conocer la enfermedad y el entorno del afectado nos ayuda a acotar para hacer una selecci\u00f3n m\u00e1s individualizada de las adaptaciones, de la educaci\u00f3n sanitaria, del material e incluso para poder respetar los tiempos que cada persona necesita para aceptar los cambios.<\/p>\n\n\n\n<p>A veces a trav\u00e9s de internet, farmacias, ortopedias o simplemente conocidos, nos informan de ayudas t\u00e9cnicas. Todas parecen efectivas y que nos solucionan los problemas, las compramos y nos damos cuenta que no acaban de funcionar. Compramos sillas que no entran por las puertas o el ascensor, cubiertos demasiado pesados, hacemos reformas del ba\u00f1o que acaban siendo peor de lo que ten\u00edamos, etc&#8230; Estamos sobre-informados y a la vez no sabemos c\u00f3mo manejar esta informaci\u00f3n que nos llega.<\/p>\n\n\n\n<p>No todo se centra en la recomendaci\u00f3n de productos de apoyo, sino que, en ocasiones, s\u00f3lo cambiando la manera de hacer una actividad nos da la independencia que hab\u00edamos perdido o nos ayuda a conservarla.<\/p>\n\n\n\n<p>Por otro lado, un entorno social beneficioso ayuda mucho en el d\u00eda a d\u00eda. Cuidadores que se dejan asesorar y no se muestran reticentes a los cambios son el punto clave para mantener una buena calidad de vida, tanto para ellos mismos como para la persona que sufre la enfermedad.<\/p>\n\n\n\n<p>Por eso desde la Fundaci\u00f3n Catalana de ELA Miquel Valls nuestro trabajo se centra en el domicilio. Para nosotros es important\u00edsimo conocer tanto el entorno f\u00edsico: la accesibilidad en el hogar, los espacios, etc&#8230; Como el entorno social: familia y cuidadores, para poder realizar una buena educaci\u00f3n sanitaria.<\/p>\n\n\n\n<h6 class=\"has-text-align-right wp-block-heading\"><em>Departamento de Terapia Ocupacional y Banco de Productos de Apoyo de la Fundaci\u00f3n Catalana de ELA Miquel Valls<\/em><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>En la Terapia Ocupacional se realiza un planteamiento hol\u00edstico de la persona, es decir, en nuestro trabajo no s\u00f3lo nos centramos en la persona afectada de ELA sino tambi\u00e9n en su entorno f\u00edsico y social. Conocer la enfermedad y el entorno del afectado nos ayuda a acotar para hacer una selecci\u00f3n m\u00e1s individualizada de las adaptaciones, de la educaci\u00f3n sanitaria, del material e incluso para poder respetar los tiempos que cada persona necesita para aceptar los cambios. A veces a trav\u00e9s de internet, farmacias, ortopedias o simplemente conocidos, nos informan de ayudas t\u00e9cnicas. Todas parecen efectivas y que nos solucionan los problemas, las compramos y nos damos cuenta que no acaban de funcionar. Compramos sillas que no entran por las puertas o el ascensor, cubiertos demasiado pesados, hacemos reformas del ba\u00f1o que acaban siendo peor de lo que ten\u00edamos, etc&#8230; Estamos sobre-informados y a la vez no sabemos c\u00f3mo manejar esta informaci\u00f3n que nos llega. No todo se centra en la recomendaci\u00f3n de productos de apoyo, sino que, en ocasiones, s\u00f3lo cambiando la manera de hacer una actividad nos da la independencia que hab\u00edamos perdido o nos ayuda a conservarla. Por otro lado, un entorno social beneficioso ayuda mucho en el d\u00eda a d\u00eda. Cuidadores que se dejan asesorar y no se muestran reticentes a los cambios son el punto clave para mantener una buena calidad de vida, tanto para ellos mismos como para la persona que sufre la enfermedad. Por eso desde la Fundaci\u00f3n Catalana de ELA Miquel Valls nuestro trabajo se centra en el domicilio. Para nosotros es important\u00edsimo conocer tanto el entorno f\u00edsico: la accesibilidad en el hogar, los espacios, etc&#8230; Como el entorno social: familia y cuidadores, para poder realizar una buena educaci\u00f3n sanitaria. Departamento de Terapia Ocupacional y Banco de Productos de Apoyo de la Fundaci\u00f3n Catalana de ELA Miquel Valls<\/p>\n","protected":false},"author":1,"featured_media":3806,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[143,161,91,122,121,94,103],"class_list":["post-3809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-dinteres","tag-banco-de-productos-de-apoyo","tag-banco-de-productos-de-apoyo-2","tag-ela-es","tag-fundacio-catalana-dela-miquel-valls-es","tag-fundacio-catalana-dela-miquel-valls","tag-terapia-ocupacional","tag-terapia-ocupacional-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El planteamiento de la Terapia Ocupacional en la Fundaci\u00f3n Miquel Valls\ufffc - Fundaci\u00f3 Catalana d&#039;ELA Miquel Valls<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls\ufffc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El planteamiento de la Terapia Ocupacional en la Fundaci\u00f3n Miquel Valls\ufffc - Fundaci\u00f3 Catalana d&#039;ELA Miquel Valls\" \/>\n<meta property=\"og:description\" content=\"En la Terapia Ocupacional se realiza un planteamiento hol\u00edstico de la persona, es decir, en nuestro trabajo no s\u00f3lo nos centramos en la persona afectada de ELA sino tambi\u00e9n en su entorno f\u00edsico y social. Conocer la enfermedad y el entorno del afectado nos ayuda a acotar para hacer una selecci\u00f3n m\u00e1s individualizada de las adaptaciones, de la educaci\u00f3n sanitaria, del material e incluso para poder respetar los tiempos que cada persona necesita para aceptar los cambios. A veces a trav\u00e9s de internet, farmacias, ortopedias o simplemente conocidos, nos informan de ayudas t\u00e9cnicas. Todas parecen efectivas y que nos solucionan los problemas, las compramos y nos damos cuenta que no acaban de funcionar. Compramos sillas que no entran por las puertas o el ascensor, cubiertos demasiado pesados, hacemos reformas del ba\u00f1o que acaban siendo peor de lo que ten\u00edamos, etc&#8230; Estamos sobre-informados y a la vez no sabemos c\u00f3mo manejar esta informaci\u00f3n que nos llega. No todo se centra en la recomendaci\u00f3n de productos de apoyo, sino que, en ocasiones, s\u00f3lo cambiando la manera de hacer una actividad nos da la independencia que hab\u00edamos perdido o nos ayuda a conservarla. Por otro lado, un entorno social beneficioso ayuda mucho en el d\u00eda a d\u00eda. Cuidadores que se dejan asesorar y no se muestran reticentes a los cambios son el punto clave para mantener una buena calidad de vida, tanto para ellos mismos como para la persona que sufre la enfermedad. Por eso desde la Fundaci\u00f3n Catalana de ELA Miquel Valls nuestro trabajo se centra en el domicilio. Para nosotros es important\u00edsimo conocer tanto el entorno f\u00edsico: la accesibilidad en el hogar, los espacios, etc&#8230; Como el entorno social: familia y cuidadores, para poder realizar una buena educaci\u00f3n sanitaria. Departamento de Terapia Ocupacional y Banco de Productos de Apoyo de la Fundaci\u00f3n Catalana de ELA Miquel Valls\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls\ufffc\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 Catalana d&#039;ELA Miquel Valls\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-19T12:36:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-19T12:47:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fundaciomiquelvalls.org\/wp-content\/uploads\/2022\/09\/ORTO-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Fundaci\u00f3 Catalana d&#039;ELA Miquel Valls\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fundaci\u00f3 Catalana d&#039;ELA Miquel Valls\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/\"},\"author\":{\"name\":\"Fundaci\u00f3 Catalana d'ELA Miquel Valls\",\"@id\":\"https:\/\/fundaciomiquelvalls.org\/#\/schema\/person\/49e4b390c29b931f8b4213fbd9276ea3\"},\"headline\":\"El planteamiento de la Terapia Ocupacional en la Fundaci\u00f3n Miquel Valls\ufffc\",\"datePublished\":\"2020-09-19T12:36:42+00:00\",\"dateModified\":\"2022-09-19T12:47:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/\"},\"wordCount\":341,\"image\":{\"@id\":\"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fundaciomiquelvalls.org\/wp-content\/uploads\/2022\/09\/ORTO.png\",\"keywords\":[\"Banco de Productos de Apoyo\",\"Banco de Productos de Apoyo\",\"ELA\",\"Fundaci\u00f3 Catalana d&#039;ELA Miquel Valls\",\"Fundaci\u00f3 Catalana d&#039;ELA Miquel Valls\",\"Ter\u00e0pia Ocupacional\",\"Ter\u00e0pia Ocupacional\"],\"articleSection\":[\"Articles d'inter\u00e8s\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/\",\"url\":\"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/\",\"name\":\"El planteamiento de la Terapia Ocupacional en la Fundaci\u00f3n Miquel Valls\ufffc - Fundaci\u00f3 Catalana d&#039;ELA Miquel Valls\",\"isPartOf\":{\"@id\":\"https:\/\/fundaciomiquelvalls.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fundaciomiquelvalls.org\/wp-content\/uploads\/2022\/09\/ORTO.png\",\"datePublished\":\"2020-09-19T12:36:42+00:00\",\"dateModified\":\"2022-09-19T12:47:28+00:00\",\"author\":{\"@id\":\"https:\/\/fundaciomiquelvalls.org\/#\/schema\/person\/49e4b390c29b931f8b4213fbd9276ea3\"},\"breadcrumb\":{\"@id\":\"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/#primaryimage\",\"url\":\"https:\/\/fundaciomiquelvalls.org\/wp-content\/uploads\/2022\/09\/ORTO.png\",\"contentUrl\":\"https:\/\/fundaciomiquelvalls.org\/wp-content\/uploads\/2022\/09\/ORTO.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/fundaciomiquelvalls.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El planteamiento de la Terapia Ocupacional en la Fundaci\u00f3n Miquel Valls\ufffc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fundaciomiquelvalls.org\/#website\",\"url\":\"https:\/\/fundaciomiquelvalls.org\/\",\"name\":\"Fundaci\u00f3 Catalana d&#039;ELA Miquel Valls\",\"description\":\"Treballem per millorar la qualitat de vida de les persones afectades d&#039;ELA i Malaltia de Motoneurona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fundaciomiquelvalls.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/fundaciomiquelvalls.org\/#\/schema\/person\/49e4b390c29b931f8b4213fbd9276ea3\",\"name\":\"Fundaci\u00f3 Catalana d'ELA Miquel Valls\",\"sameAs\":[\"https:\/\/fundaciomiquelvalls.org\"],\"url\":\"https:\/\/fundaciomiquelvalls.org\/es\/author\/alojapro_dev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El planteamiento de la Terapia Ocupacional en la Fundaci\u00f3n Miquel Valls\ufffc - Fundaci\u00f3 Catalana d&#039;ELA Miquel Valls","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls\ufffc\/","og_locale":"es_ES","og_type":"article","og_title":"El planteamiento de la Terapia Ocupacional en la Fundaci\u00f3n Miquel Valls\ufffc - Fundaci\u00f3 Catalana d&#039;ELA Miquel Valls","og_description":"En la Terapia Ocupacional se realiza un planteamiento hol\u00edstico de la persona, es decir, en nuestro trabajo no s\u00f3lo nos centramos en la persona afectada de ELA sino tambi\u00e9n en su entorno f\u00edsico y social. Conocer la enfermedad y el entorno del afectado nos ayuda a acotar para hacer una selecci\u00f3n m\u00e1s individualizada de las adaptaciones, de la educaci\u00f3n sanitaria, del material e incluso para poder respetar los tiempos que cada persona necesita para aceptar los cambios. A veces a trav\u00e9s de internet, farmacias, ortopedias o simplemente conocidos, nos informan de ayudas t\u00e9cnicas. Todas parecen efectivas y que nos solucionan los problemas, las compramos y nos damos cuenta que no acaban de funcionar. Compramos sillas que no entran por las puertas o el ascensor, cubiertos demasiado pesados, hacemos reformas del ba\u00f1o que acaban siendo peor de lo que ten\u00edamos, etc&#8230; Estamos sobre-informados y a la vez no sabemos c\u00f3mo manejar esta informaci\u00f3n que nos llega. No todo se centra en la recomendaci\u00f3n de productos de apoyo, sino que, en ocasiones, s\u00f3lo cambiando la manera de hacer una actividad nos da la independencia que hab\u00edamos perdido o nos ayuda a conservarla. Por otro lado, un entorno social beneficioso ayuda mucho en el d\u00eda a d\u00eda. Cuidadores que se dejan asesorar y no se muestran reticentes a los cambios son el punto clave para mantener una buena calidad de vida, tanto para ellos mismos como para la persona que sufre la enfermedad. Por eso desde la Fundaci\u00f3n Catalana de ELA Miquel Valls nuestro trabajo se centra en el domicilio. Para nosotros es important\u00edsimo conocer tanto el entorno f\u00edsico: la accesibilidad en el hogar, los espacios, etc&#8230; Como el entorno social: familia y cuidadores, para poder realizar una buena educaci\u00f3n sanitaria. Departamento de Terapia Ocupacional y Banco de Productos de Apoyo de la Fundaci\u00f3n Catalana de ELA Miquel Valls","og_url":"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls\ufffc\/","og_site_name":"Fundaci\u00f3 Catalana d&#039;ELA Miquel Valls","article_published_time":"2020-09-19T12:36:42+00:00","article_modified_time":"2022-09-19T12:47:28+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/fundaciomiquelvalls.org\/wp-content\/uploads\/2022\/09\/ORTO-1024x576.png","type":"image\/png"}],"author":"Fundaci\u00f3 Catalana d'ELA Miquel Valls","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fundaci\u00f3 Catalana d'ELA Miquel Valls","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/#article","isPartOf":{"@id":"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/"},"author":{"name":"Fundaci\u00f3 Catalana d'ELA Miquel Valls","@id":"https:\/\/fundaciomiquelvalls.org\/#\/schema\/person\/49e4b390c29b931f8b4213fbd9276ea3"},"headline":"El planteamiento de la Terapia Ocupacional en la Fundaci\u00f3n Miquel Valls\ufffc","datePublished":"2020-09-19T12:36:42+00:00","dateModified":"2022-09-19T12:47:28+00:00","mainEntityOfPage":{"@id":"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/"},"wordCount":341,"image":{"@id":"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/#primaryimage"},"thumbnailUrl":"https:\/\/fundaciomiquelvalls.org\/wp-content\/uploads\/2022\/09\/ORTO.png","keywords":["Banco de Productos de Apoyo","Banco de Productos de Apoyo","ELA","Fundaci\u00f3 Catalana d&#039;ELA Miquel Valls","Fundaci\u00f3 Catalana d&#039;ELA Miquel Valls","Ter\u00e0pia Ocupacional","Ter\u00e0pia Ocupacional"],"articleSection":["Articles d'inter\u00e8s"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/","url":"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/","name":"El planteamiento de la Terapia Ocupacional en la Fundaci\u00f3n Miquel Valls\ufffc - Fundaci\u00f3 Catalana d&#039;ELA Miquel Valls","isPartOf":{"@id":"https:\/\/fundaciomiquelvalls.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/#primaryimage"},"image":{"@id":"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/#primaryimage"},"thumbnailUrl":"https:\/\/fundaciomiquelvalls.org\/wp-content\/uploads\/2022\/09\/ORTO.png","datePublished":"2020-09-19T12:36:42+00:00","dateModified":"2022-09-19T12:47:28+00:00","author":{"@id":"https:\/\/fundaciomiquelvalls.org\/#\/schema\/person\/49e4b390c29b931f8b4213fbd9276ea3"},"breadcrumb":{"@id":"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/#primaryimage","url":"https:\/\/fundaciomiquelvalls.org\/wp-content\/uploads\/2022\/09\/ORTO.png","contentUrl":"https:\/\/fundaciomiquelvalls.org\/wp-content\/uploads\/2022\/09\/ORTO.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/fundaciomiquelvalls.org\/el-plantejament-de-la-terapia-ocupacional-a-la-fundacio-catalana-dela-miquel-valls%ef%bf%bc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundaciomiquelvalls.org\/es\/"},{"@type":"ListItem","position":2,"name":"El planteamiento de la Terapia Ocupacional en la Fundaci\u00f3n Miquel Valls\ufffc"}]},{"@type":"WebSite","@id":"https:\/\/fundaciomiquelvalls.org\/#website","url":"https:\/\/fundaciomiquelvalls.org\/","name":"Fundaci\u00f3 Catalana d&#039;ELA Miquel Valls","description":"Treballem per millorar la qualitat de vida de les persones afectades d&#039;ELA i Malaltia de Motoneurona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundaciomiquelvalls.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/fundaciomiquelvalls.org\/#\/schema\/person\/49e4b390c29b931f8b4213fbd9276ea3","name":"Fundaci\u00f3 Catalana d'ELA Miquel Valls","sameAs":["https:\/\/fundaciomiquelvalls.org"],"url":"https:\/\/fundaciomiquelvalls.org\/es\/author\/alojapro_dev\/"}]}},"_links":{"self":[{"href":"https:\/\/fundaciomiquelvalls.org\/es\/wp-json\/wp\/v2\/posts\/3809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundaciomiquelvalls.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundaciomiquelvalls.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundaciomiquelvalls.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fundaciomiquelvalls.org\/es\/wp-json\/wp\/v2\/comments?post=3809"}],"version-history":[{"count":1,"href":"https:\/\/fundaciomiquelvalls.org\/es\/wp-json\/wp\/v2\/posts\/3809\/revisions"}],"predecessor-version":[{"id":3811,"href":"https:\/\/fundaciomiquelvalls.org\/es\/wp-json\/wp\/v2\/posts\/3809\/revisions\/3811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundaciomiquelvalls.org\/es\/wp-json\/wp\/v2\/media\/3806"}],"wp:attachment":[{"href":"https:\/\/fundaciomiquelvalls.org\/es\/wp-json\/wp\/v2\/media?parent=3809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundaciomiquelvalls.org\/es\/wp-json\/wp\/v2\/categories?post=3809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundaciomiquelvalls.org\/es\/wp-json\/wp\/v2\/tags?post=3809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}